﻿{"id":1686,"count":1,"description":"","link":"https:\/\/www.gameovert.net\/site\/tag\/perspective\/","name":"Perspective","slug":"perspective","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perspective Archives - GameOvert.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gameovert.net\/site\/tag\/perspective\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perspective Archives - GameOvert.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gameovert.net\/site\/tag\/perspective\/\" \/>\n<meta property=\"og:site_name\" content=\"GameOvert.net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Gameovertnet\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/tag\\\/perspective\\\/\",\"url\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/tag\\\/perspective\\\/\",\"name\":\"Perspective Archives - GameOvert.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/tag\\\/perspective\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/tag\\\/perspective\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perspective\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/\",\"name\":\"GameOvert.net\",\"description\":\"Le blog sur les jeux et les joueurs depuis 16 g\u00e9n\u00e9rations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/#organization\",\"name\":\"Gameovert.net\",\"url\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logopetit.png\",\"contentUrl\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logopetit.png\",\"width\":200,\"height\":200,\"caption\":\"Gameovert.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gameovert.net\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gameovert.net\",\"https:\\\/\\\/x.com\\\/Gameovertnet\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZLbVo6j-xAlkFfL5bGZkOg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perspective Archives - GameOvert.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gameovert.net\/site\/tag\/perspective\/","og_locale":"fr_FR","og_type":"article","og_title":"Perspective Archives - GameOvert.net","og_url":"https:\/\/www.gameovert.net\/site\/tag\/perspective\/","og_site_name":"GameOvert.net","twitter_card":"summary_large_image","twitter_site":"@Gameovertnet","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.gameovert.net\/site\/tag\/perspective\/","url":"https:\/\/www.gameovert.net\/site\/tag\/perspective\/","name":"Perspective Archives - GameOvert.net","isPartOf":{"@id":"https:\/\/www.gameovert.net\/site\/#website"},"breadcrumb":{"@id":"https:\/\/www.gameovert.net\/site\/tag\/perspective\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gameovert.net\/site\/tag\/perspective\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gameovert.net\/site\/"},{"@type":"ListItem","position":2,"name":"Perspective"}]},{"@type":"WebSite","@id":"https:\/\/www.gameovert.net\/site\/#website","url":"https:\/\/www.gameovert.net\/site\/","name":"GameOvert.net","description":"Le blog sur les jeux et les joueurs depuis 16 g\u00e9n\u00e9rations","publisher":{"@id":"https:\/\/www.gameovert.net\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gameovert.net\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.gameovert.net\/site\/#organization","name":"Gameovert.net","url":"https:\/\/www.gameovert.net\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gameovert.net\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.gameovert.net\/site\/wp-content\/uploads\/2015\/10\/logopetit.png","contentUrl":"https:\/\/www.gameovert.net\/site\/wp-content\/uploads\/2015\/10\/logopetit.png","width":200,"height":200,"caption":"Gameovert.net"},"image":{"@id":"https:\/\/www.gameovert.net\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gameovert.net","https:\/\/x.com\/Gameovertnet","https:\/\/www.youtube.com\/channel\/UCZLbVo6j-xAlkFfL5bGZkOg"]}]}},"_links":{"self":[{"href":"https:\/\/www.gameovert.net\/site\/wp-json\/wp\/v2\/tags\/1686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gameovert.net\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.gameovert.net\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.gameovert.net\/site\/wp-json\/wp\/v2\/posts?tags=1686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}